{"id":100827,"date":"2024-09-22T06:16:38","date_gmt":"2024-09-22T03:16:38","guid":{"rendered":"https:\/\/www.mahhalcom.com\/?post_type=product&#038;p=100827"},"modified":"2025-09-23T14:41:33","modified_gmt":"2025-09-23T11:41:33","slug":"anti-snoring-sprays-fast-relief","status":"publish","type":"product","link":"https:\/\/mahhalcom.com\/ar\/product\/anti-snoring-sprays-fast-relief\/","title":{"rendered":"\u0628\u062e\u0627\u062e\u0627\u062a \u0645\u0636\u0627\u062f\u0629 \u0644\u0644\u0634\u062e\u064a\u0631 \u0644\u062a\u062e\u0641\u064a\u0641 \u0633\u0631\u064a\u0639"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div class=\"product-specs-list-container\">\n<ul class=\"product-specs-list util-clearfix\">\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">\u0639\u062f\u062f \u0627\u0644\u0642\u0637\u0639:\u00a0<\/span><span class=\"property-desc line-limit-length\">\u0648\u062d\u062f\u0629 \u0648\u0627\u062d\u062f\u0629<\/span><\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">\u0631\u0642\u0645 \u0627\u0644\u0645\u0648\u062f\u064a\u0644:\u00a0<\/span><span class=\"property-desc line-limit-length\">\u0628\u062e\u0627\u062e \u0645\u0636\u0627\u062f \u0644\u0644\u0634\u062e\u064a\u0631<\/span><\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">\u064a\u0643\u062a\u0628:\u00a0<\/span><span class=\"property-desc line-limit-length\">\u0622\u062e\u0631<\/span><\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">\u0646\u0648\u0639 \u0627\u0644\u0645\u0646\u062a\u062c:\u00a0<\/span><span class=\"property-desc line-limit-length\">\u0627\u0644\u0646\u0648\u0645 \u0648\u0627\u0644\u0634\u062e\u064a\u0631<\/span><\/li>\n<\/ul>\n<\/div>\n<div class=\"detailmodule_text\">\n<p class=\"detail-desc-decorate-content\" style=\"font-family: OpenSans; font-size: 14px; font-weight: 300; line-height: 20px; white-space: pre-wrap; color: #000000; margin-bottom: 12px;\">\u0645\u064a\u0632\u0629:<br \/>\n\u064a\u0631\u062c\u0649 \u0627\u0644\u0645\u0644\u0627\u062d\u0638\u0629: \u0627\u0644\u0645\u0644\u062d\u0642\u0627\u062a \u0627\u0644\u0623\u062e\u0631\u0649 \u063a\u064a\u0631 \u0645\u0634\u0645\u0648\u0644\u0629.<br \/>\n100% \u062c\u0648\u062f\u0629 \u062c\u062f\u064a\u062f\u0629<\/p>\n<p>\u0627\u0644\u062d\u0632\u0645\u0629 \u062a\u0634\u0645\u0644:<br \/>\n\u0628\u062e\u0627\u062e \u0648\u0627\u062d\u062f \u0645\u0636\u0627\u062f \u0644\u0644\u0634\u062e\u064a\u0631<\/p>\n<\/div>\n<div class=\"detailmodule_image\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"detail-desc-decorate-image aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/S23aeb04ef1514eb18a811749a065ed3cE.jpg?w=1020&#038;ssl=1\" \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"detail-desc-decorate-image aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/S5ba54b84bf534f43908e736cee560c71W.jpg?w=1020&#038;ssl=1\" \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"detail-desc-decorate-image aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/Seebc8b42069f401bbae3a49a35e77061R.jpg?w=1020&#038;ssl=1\" \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"detail-desc-decorate-image aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/S5b1f41fae15a4519b65c38ac8ed6c8f2O.jpg?w=1020&#038;ssl=1\" \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"detail-desc-decorate-image aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/S9d1348b931154ae8b41c2a30d4508877j.jpg?w=1020&#038;ssl=1\" \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"detail-desc-decorate-image aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/Sa8bed370a39c48919933649e4664f212m.jpg?w=1020&#038;ssl=1\" \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"detail-desc-decorate-image aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/Sb90758c78b5344fd9094bdc0fa8fe9c6z.jpg?w=1020&#038;ssl=1\" \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"detail-desc-decorate-image aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/S9470bd19c0dc4dd6ab3895929f263b21B.jpg?w=1020&#038;ssl=1\" \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"detail-desc-decorate-image aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/Scecfb836ef324f8ea0994a5635e69291V.jpg?w=1020&#038;ssl=1\" \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"detail-desc-decorate-image aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/S1c1d467a3a784f98a8fd004430334662j.jpg?w=1020&#038;ssl=1\" \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"detail-desc-decorate-image aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/S660ec98fd85846aba9d5bb52926a69f6N.jpg?w=1020&#038;ssl=1\" \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"detail-desc-decorate-image aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/Sb902c26532004650b3304ec0f4f148cfC.jpg?w=1020&#038;ssl=1\" \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"detail-desc-decorate-image aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/S4233b47c32384fbeb86e312396441baas.jpg?w=1020&#038;ssl=1\" \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"detail-desc-decorate-image aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/Sffb9800f4cef44f8ad39a34ee64d6e953.jpg?w=1020&#038;ssl=1\" \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"detail-desc-decorate-image aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/S15ffe22567874911b88f875a2fefddc76.jpg?w=1020&#038;ssl=1\" \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"detail-desc-decorate-image aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/S3f71e019a9444e72822f39d6cb1f990bS.jpg?w=1020&#038;ssl=1\" \/><\/div>\n<div class=\"detailmodule_text\">\n<p class=\"detail-desc-decorate-content\" style=\"font-family: OpenSans; font-size: 14px; font-weight: 300; line-height: 20px; white-space: pre-wrap; color: #000000; margin-bottom: 12px;\">\n<\/div>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>\u0628\u062e\u0627\u062e\u0627\u062a \u0645\u0636\u0627\u062f\u0629 \u0644\u0644\u0634\u062e\u064a\u0631\u060c \u0628\u062e\u0627\u062e\u0627\u062a \u0645\u0632\u064a\u0644\u0629 \u0644\u0644\u0627\u062d\u062a\u0642\u0627\u0646 \u0644\u0644\u0623\u0646\u0641\u060c \u062a\u0641\u062a\u062d \u0642\u0646\u0648\u0627\u062a \u0627\u0644\u0623\u0630\u0646 \u0648\u0627\u0644\u062c\u064a\u0648\u0628 \u0627\u0644\u0623\u0646\u0641\u064a\u0629 \u0627\u0644\u0645\u0633\u062f\u0648\u062f\u0629\u060c \u062a\u0633\u0643\u064a\u0646 \u0627\u0644\u062d\u0644\u0642\u060c \u0628\u062e\u0627\u062e\u0627\u062a \u0644\u0648\u0642\u0641 \u0627\u0644\u0634\u062e\u064a\u0631<\/p>","protected":false},"featured_media":100828,"comment_status":"closed","ping_status":"closed","template":"","meta":{"jetpack_post_was_ever_published":false,"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"product_brand":[],"product_cat":[156,424],"product_tag":[],"class_list":{"0":"post-100827","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-medical","7":"product_cat-snore-spray","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"product-type-simple"},"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/mahhalcom.com\/ar\/wp-json\/wp\/v2\/product\/100827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mahhalcom.com\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mahhalcom.com\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mahhalcom.com\/ar\/wp-json\/wp\/v2\/comments?post=100827"}],"version-history":[{"count":0,"href":"https:\/\/mahhalcom.com\/ar\/wp-json\/wp\/v2\/product\/100827\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mahhalcom.com\/ar\/wp-json\/wp\/v2\/media\/100828"}],"wp:attachment":[{"href":"https:\/\/mahhalcom.com\/ar\/wp-json\/wp\/v2\/media?parent=100827"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mahhalcom.com\/ar\/wp-json\/wp\/v2\/product_brand?post=100827"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mahhalcom.com\/ar\/wp-json\/wp\/v2\/product_cat?post=100827"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mahhalcom.com\/ar\/wp-json\/wp\/v2\/product_tag?post=100827"}],"curies":[{"name":"\u0648\u0648\u0631\u062f\u0628\u0631\u064a\u0633","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}