{"id":102213,"date":"2024-09-26T17:59:47","date_gmt":"2024-09-26T14:59:47","guid":{"rendered":"https:\/\/www.mahhalcom.com\/?post_type=product&#038;p=102213"},"modified":"2026-04-20T08:57:10","modified_gmt":"2026-04-20T05:57:10","slug":"guardrail-child-safety","status":"publish","type":"product","link":"https:\/\/mahhalcom.com\/ar\/product\/guardrail-child-safety\/","title":{"rendered":"\u062d\u0627\u062c\u0632 \u0623\u0645\u0627\u0646 \u0644\u062d\u0645\u0627\u064a\u0629 \u0627\u0644\u0637\u0641\u0644"},"content":{"rendered":"<div class=\"product-specs-list-container\" style=\"text-align: center;\">\n<ul class=\"product-specs-list util-clearfix\">\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">\u0645\u0627\u062f\u0629 \u0643\u064a\u0645\u064a\u0627\u0626\u064a\u0629 \u0630\u0627\u062a \u0623\u0647\u0645\u064a\u0629 \u0628\u0627\u0644\u063a\u0629:\u00a0<\/span><span class=\"property-desc line-limit-length\">\u0644\u0627 \u0623\u062d\u062f<\/span><\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">\u0631\u0642\u0645 \u0627\u0644\u0635\u0646\u0641:\u00a0<\/span><span class=\"property-desc line-limit-length\">SSG-1<\/span><\/li>\n<li class=\"product-prop line-limit-length\"><span class=\"property-title\">\u0646\u0648\u0639 \u0627\u0644\u062a\u063a\u0644\u064a\u0641:\u00a0<\/span><span class=\"property-desc line-limit-length\">\u0627\u0644\u062a\u0639\u0628\u0626\u0629 \u0627\u0644\u0623\u0633\u0627\u0633\u064a\u0629<\/span><\/li>\n<\/ul>\n<\/div>\n<div class=\"detailmodule_html\">\n<div class=\"detail-desc-decorate-richtext\">\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/Sa99404c363674979a54ad4c3eb10cabed.jpg?w=620&#038;ssl=1\"  \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/S4faacb48dddc4d53bc447b3cab4022a92.jpg?w=620&#038;ssl=1\"  \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/S2f446e1fdf2c4695a8e10b93b9f544926.jpg?w=620&#038;ssl=1\"  \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/S50f8ee520a3b47218a61eba0ab502e332.jpg?w=620&#038;ssl=1\"  \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/Sabc736cb996a402294f3b8e44143db25X.jpg?w=620&#038;ssl=1\"  \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/Sc7e926231fc447bca39df2dbd222af30t.jpg?w=620&#038;ssl=1\"  \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/Saef893feda16421d87ce92c2c661ce6b6.jpg?w=620&#038;ssl=1\"  \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/S4a3e4b64208b4a7db277994f163ff484T.jpg?w=620&#038;ssl=1\"  \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/Sf4036a2b76074d6f85580d825d1efea1r.jpg?w=620&#038;ssl=1\"  \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/S8ba0bdf74ed44643b060131bb67fc4d7Q.jpg?w=620&#038;ssl=1\"  \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/S3fc62677d8c7485f994eee0901fef41aM.jpg?w=620&#038;ssl=1\"  \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/Sde2fa50f11ee47ca94fcc967dd581af7q.jpg?w=620&#038;ssl=1\"  \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/Sf8e13f18f17e4cdbaf48cb41598406a4k.jpg?w=620&#038;ssl=1\"  \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/S9302875a68374842829a761d3b27ad2aq.jpg?w=620&#038;ssl=1\"  \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/Sd08e5efba9254080bf2e4b07468c4970s.jpg?w=620&#038;ssl=1\"  \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/S061d239701b343e1aebcca1a4ef53e92M.jpg?w=620&#038;ssl=1\"  \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/S9ed175ff61804198b073b08ab6e95a00Y.jpg?w=620&#038;ssl=1\"  \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/S064c31b62a0d4dc6afa54757a61e6090c.jpg?w=620&#038;ssl=1\"  \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/Sb205c5342a7e4aaab32e986bbf48146fS.jpg?w=620&#038;ssl=1\"  \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/S66fd8b04ad6f4ae2ab384192c3be2f59O.jpg?w=620&#038;ssl=1\"  \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/S249462d2c46b42f68a632327a3ae1f400.jpg?w=620&#038;ssl=1\"  \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/S4b9adddd9b90469b9481cb53a49eea26E.jpg?w=620&#038;ssl=1\"  \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/S4944a280f83c43f89bdff59fa23cd329s.jpg?w=620&#038;ssl=1\"  \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/S31e066d09425412487d573decfb5d46a7.jpg?w=620&#038;ssl=1\"  \/><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i0.wp.com\/ae01.alicdn.com\/kf\/S93561265bac943ea9dd341e94411edf2q.jpg?w=620&#038;ssl=1\"  \/><\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u062f\u0631\u0627\u0628\u0632\u064a\u0646 \u0644\u0644\u0633\u0644\u0627\u0644\u0645\u060c \u0633\u064a\u0627\u062c \u0623\u0645\u0627\u0646 \u0644\u0644\u0623\u0637\u0641\u0627\u0644 \u0639\u0646\u062f \u0627\u0644\u0623\u0628\u0648\u0627\u0628\u060c \u062f\u0631\u0627\u0628\u0632\u064a\u0646 \u0642\u0627\u0628\u0644 \u0644\u0644\u0637\u064a \u0648\u0627\u0644\u0633\u062d\u0628\u060c \u062d\u0627\u062c\u0632 \u0623\u0645\u0627\u0646 \u0644\u0644\u0623\u0637\u0641\u0627\u0644 \u0639\u0646\u062f \u0627\u0644\u0623\u0628\u0648\u0627\u0628\u060c \u0642\u0636\u064a\u0628 \u0633\u064a\u0627\u062c \u0644\u0644\u062d\u064a\u0648\u0627\u0646\u0627\u062a \u0627\u0644\u0623\u0644\u064a\u0641\u0629 \u0641\u064a \u0627\u0644\u0645\u0637\u0628\u062e<\/p>","protected":false},"featured_media":102233,"comment_status":"closed","ping_status":"closed","template":"","meta":{"jetpack_post_was_ever_published":false,"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"product_brand":[],"product_cat":[351,252,250,270,152],"product_tag":[],"class_list":{"0":"post-102213","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-baby-care","7":"product_cat-bed-room-accessories","8":"product_cat-home","9":"product_cat-home-supplies","10":"product_cat-kids-babies","12":"first","13":"instock","14":"sale","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/mahhalcom.com\/ar\/wp-json\/wp\/v2\/product\/102213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mahhalcom.com\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mahhalcom.com\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mahhalcom.com\/ar\/wp-json\/wp\/v2\/comments?post=102213"}],"version-history":[{"count":0,"href":"https:\/\/mahhalcom.com\/ar\/wp-json\/wp\/v2\/product\/102213\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mahhalcom.com\/ar\/wp-json\/wp\/v2\/media\/102233"}],"wp:attachment":[{"href":"https:\/\/mahhalcom.com\/ar\/wp-json\/wp\/v2\/media?parent=102213"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mahhalcom.com\/ar\/wp-json\/wp\/v2\/product_brand?post=102213"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mahhalcom.com\/ar\/wp-json\/wp\/v2\/product_cat?post=102213"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mahhalcom.com\/ar\/wp-json\/wp\/v2\/product_tag?post=102213"}],"curies":[{"name":"\u0648\u0648\u0631\u062f\u0628\u0631\u064a\u0633","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}